{"id":100,"count":1,"description":"","link":"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/","name":"Construction Shop Drawings","slug":"construction-shop-drawings","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"google-site-verification=aveVD_Z19mN5V-hIWO2lbm28Z3QtVanQxBx6OBxIQ84\" \/>\n\t<meta name=\"msvalidate.01\" content=\"dfa4f458e4864a6484dc0f01fe0dde8d\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Steel Detailing India - Blog - Steel Detailing Company India - Blog\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Construction Shop Drawings - Steel Detailing India - Blog\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.steeldetailingindia.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-Steel-Detailing-India-01.png?fit=4167%2C1382&#038;ssl=1\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/www.steeldetailingindia.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-Steel-Detailing-India-01.png?fit=4167%2C1382&#038;ssl=1\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/7solutionsdrafting\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Construction Shop Drawings - Steel Detailing India - Blog\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/www.steeldetailingindia.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-Steel-Detailing-India-01.png?fit=4167%2C1382&amp;ssl=1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/100\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/tag\\\/construction-shop-drawings\\\/#listItem\",\"name\":\"Construction Shop Drawings\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/tag\\\/construction-shop-drawings\\\/#listItem\",\"position\":2,\"name\":\"Construction Shop Drawings\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/100\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/100\\\/\",\"name\":\"Construction Shop Drawings - Steel Detailing India - Blog\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/100\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/#organization\",\"name\":\"Steel Detailing India-Blog\",\"description\":\"Steel Detailing Company India - Blog\",\"url\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/\",\"telephone\":\"+18705215212\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.steeldetailingindia.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Steel-Detailing-India-01.png?fit=4167%2C4167&ssl=1\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/100\\\/#organizationLogo\",\"width\":4167,\"height\":4167,\"caption\":\"Steel Detailing India\"},\"image\":{\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/100\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/7solutionsdrafting\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/7solutions-india\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/\",\"name\":\"Steel Detailing India - Blog\",\"alternateName\":\"Steel Detailing India\",\"description\":\"Steel Detailing Company India - Blog\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.steeldetailingindia.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Construction Shop Drawings - Steel Detailing India - Blog<\/title>\n\n","aioseo_head_json":{"title":"Construction Shop Drawings - Steel Detailing India - Blog","description":"","canonical_url":"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"google-site-verification=aveVD_Z19mN5V-hIWO2lbm28Z3QtVanQxBx6OBxIQ84","msvalidate.01":"dfa4f458e4864a6484dc0f01fe0dde8d","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags\/100\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.steeldetailingindia.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.steeldetailingindia.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/#listItem","name":"Construction Shop Drawings"}},{"@type":"ListItem","@id":"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/#listItem","position":2,"name":"Construction Shop Drawings","previousItem":{"@type":"ListItem","@id":"https:\/\/www.steeldetailingindia.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags\/100\/#collectionpage","url":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags\/100\/","name":"Construction Shop Drawings - Steel Detailing India - Blog","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.steeldetailingindia.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags\/100\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.steeldetailingindia.com\/blog\/#organization","name":"Steel Detailing India-Blog","description":"Steel Detailing Company India - Blog","url":"https:\/\/www.steeldetailingindia.com\/blog\/","telephone":"+18705215212","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.steeldetailingindia.com\/blog\/wp-content\/uploads\/2022\/10\/Steel-Detailing-India-01.png?fit=4167%2C4167&ssl=1","@id":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags\/100\/#organizationLogo","width":4167,"height":4167,"caption":"Steel Detailing India"},"image":{"@id":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags\/100\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/7solutionsdrafting\/","https:\/\/www.linkedin.com\/company\/7solutions-india\/"]},{"@type":"WebSite","@id":"https:\/\/www.steeldetailingindia.com\/blog\/#website","url":"https:\/\/www.steeldetailingindia.com\/blog\/","name":"Steel Detailing India - Blog","alternateName":"Steel Detailing India","description":"Steel Detailing Company India - Blog","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.steeldetailingindia.com\/blog\/#organization"}}]},"og:locale":"en_US","og:site_name":"Steel Detailing India - Blog - Steel Detailing Company India - Blog","og:type":"article","og:title":"Construction Shop Drawings - Steel Detailing India - Blog","og:url":"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/","og:image":"https:\/\/i0.wp.com\/www.steeldetailingindia.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-Steel-Detailing-India-01.png?fit=4167%2C1382&#038;ssl=1","og:image:secure_url":"https:\/\/i0.wp.com\/www.steeldetailingindia.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-Steel-Detailing-India-01.png?fit=4167%2C1382&#038;ssl=1","article:publisher":"https:\/\/www.facebook.com\/7solutionsdrafting\/","twitter:card":"summary","twitter:title":"Construction Shop Drawings - Steel Detailing India - Blog","twitter:image":"https:\/\/i0.wp.com\/www.steeldetailingindia.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-Steel-Detailing-India-01.png?fit=4167%2C1382&ssl=1"},"aioseo_meta_data":{"term_id":"100","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"tabs":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:38:31","breadcrumb_settings":null,"created":"2025-08-15 06:28:39","updated":"2026-05-13 11:38:31","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"pillar_content":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.steeldetailingindia.com\/blog\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tConstruction Shop Drawings\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.steeldetailingindia.com\/blog"},{"label":"Construction Shop Drawings","link":"https:\/\/www.steeldetailingindia.com\/blog\/tag\/construction-shop-drawings\/"}],"_links":{"self":[{"href":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.steeldetailingindia.com\/blog\/wp-json\/wp\/v2\/posts?tags=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}